{"id":3375,"date":"2026-03-25T07:14:27","date_gmt":"2026-03-25T07:14:27","guid":{"rendered":"https:\/\/hyclight.com\/?p=3375"},"modified":"2026-05-14T06:28:02","modified_gmt":"2026-05-14T06:28:02","slug":"poste-de-luz-comercial","status":"publish","type":"post","link":"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/","title":{"rendered":"Poste de ilumina\u00e7\u00e3o comercial"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3375\" class=\"elementor elementor-3375\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-105f9269 e-flex e-con-boxed e-con e-parent\" data-id=\"105f9269\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-74719015 e-con-full swap-wrap e-flex e-con e-child\" data-id=\"74719015\" data-element_type=\"container\" data-e-type=\"container\" product-gallery-wrap=\"\">\n\t\t<div class=\"elementor-element elementor-element-34b1cec6 e-con-full e-flex e-con e-child\" data-id=\"34b1cec6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5376acde elementor-widget elementor-widget-gallery\" data-id=\"5376acde\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;1:1&quot;,&quot;columns_tablet&quot;:10,&quot;columns_mobile&quot;:5,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/14-STREET-LIGHT-POLE-SHAPE.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5376acde\" data-elementor-lightbox-title=\"Blue Feather Street Light Pole Motif\" data-elementor-lightbox-description=\"This image shows a blue feather street light pole motif designed for outdoor festive decoration. Featuring elegant blue illuminated curves with star accents, this pole-mounted decorative light is suitable for city streets, shopping districts, holiday lighting displays, and commercial outdoor decoration projects.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI3NSwidXJsIjoiaHR0cHM6XC9cL2h5Y2xpZ2h0LmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDNcLzE0LVNUUkVFVC1MSUdIVC1QT0xFLVNIQVBFLmpwZyIsInNsaWRlc2hvdyI6IjUzNzZhY2RlIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/14-STREET-LIGHT-POLE-SHAPE-300x300.jpg\" data-width=\"300\" data-height=\"300\" aria-label=\"Motivo de poste de ilumina\u00e7\u00e3o p\u00fablica com penas azuis e detalhes em estrela para uma decora\u00e7\u00e3o festiva no exterior\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14dd0952 e-con-full e-flex e-con e-child\" data-id=\"14dd0952\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31b9f575 elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"31b9f575\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 \/ 1\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/14-STREET-LIGHT-POLE-SHAPE.jpg\" alt=\"Motivo de poste de ilumina\u00e7\u00e3o p\u00fablica com penas azuis e detalhes em estrela para uma decora\u00e7\u00e3o festiva no exterior\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-71f8dad e-con-full e-flex e-con e-child\" data-id=\"71f8dad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86184b7 elementor-widget elementor-widget-heading\" data-id=\"86184b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Poste de ilumina\u00e7\u00e3o comercial<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c783090 elementor-widget elementor-widget-heading\" data-id=\"5c783090\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Elegante ilumina\u00e7\u00e3o com motivos azuis em poste, concebida para estradas festivas, avenidas p\u00fablicas e projectos comerciais de decora\u00e7\u00e3o exterior.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3f9ff4 elementor-widget elementor-widget-text-editor\" data-id=\"5f3f9ff4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A nossa L\u00e2mpada com motivo de poste 2D Blue Feather foi concebida para projectos de ilumina\u00e7\u00e3o decorativa exterior que requerem uma apresenta\u00e7\u00e3o elegante e apelativa na rua. Instalado em postes de ilumina\u00e7\u00e3o e postes de avenidas, acrescenta um efeito visual elegante \u00e0s estradas da cidade, zonas comerciais, parques, rotas c\u00e9nicas e espa\u00e7os p\u00fablicos festivos. Com curvas iluminadas a azul e acentos de estrelas, este motivo decorativo \u00e9 adequado para o Natal, o Ano Novo, programas sazonais da cidade e exposi\u00e7\u00f5es comerciais no exterior. A HOYECHI fornece produ\u00e7\u00e3o direta da f\u00e1brica, fornecimento por grosso e personaliza\u00e7\u00e3o de projectos para munic\u00edpios, empreiteiros, distribuidores e compradores de ilumina\u00e7\u00e3o festiva.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb3edb8 elementor-grid-1 elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"6cb3edb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:&quot;356&quot;,&quot;columns&quot;:1,&quot;columns_tablet&quot;:1,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-356\">.elementor-356 .elementor-element.elementor-element-24e6347{--display:flex;}.elementor-widget-button .elementor-button{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );background-color:var( --e-global-color-accent );}.elementor-356 .elementor-element.elementor-element-72f55e0 .elementor-button{background-color:#E2820A;}.elementor-356 .elementor-element.elementor-element-72f55e0 .elementor-button:hover, .elementor-356 .elementor-element.elementor-element-72f55e0 .elementor-button:focus{color:#E2820A;background-color:#FFFFFF;}.elementor-356 .elementor-element.elementor-element-72f55e0 .elementor-button:hover svg, .elementor-356 .elementor-element.elementor-element-72f55e0 .elementor-button:focus svg{fill:#E2820A;}.elementor-356 .elementor-element.elementor-element-72f55e0{width:var( --container-widget-width, 50% );max-width:50%;--container-widget-width:50%;--container-widget-flex-grow:0;}.elementor-356 .elementor-element.elementor-element-65ed0a3 .elementor-button-content-wrapper{flex-direction:row;}.elementor-356 .elementor-element.elementor-element-65ed0a3 .elementor-button .elementor-button-content-wrapper{gap:0px;}.elementor-356 .elementor-element.elementor-element-65ed0a3 .elementor-button{font-family:\"Roboto\", Sans-serif;font-size:15px;font-weight:500;fill:#FFFFFF;color:#FFFFFF;background-color:#E2820A;}.elementor-356 .elementor-element.elementor-element-65ed0a3 .elementor-button:hover, .elementor-356 .elementor-element.elementor-element-65ed0a3 .elementor-button:focus{color:#E2820A;background-color:#FFFFFF;}.elementor-356 .elementor-element.elementor-element-65ed0a3 .elementor-button:hover svg, .elementor-356 .elementor-element.elementor-element-65ed0a3 .elementor-button:focus svg{fill:#E2820A;}.elementor-356 .elementor-element.elementor-element-65ed0a3{width:var( --container-widget-width, 50% );max-width:50%;--container-widget-width:50%;--container-widget-flex-grow:0;}.elementor-widget-icon-list .elementor-icon-list-item:not(:last-child):after{border-color:var( --e-global-color-text );}.elementor-widget-icon-list .elementor-icon-list-icon i{color:var( --e-global-color-primary );}.elementor-widget-icon-list .elementor-icon-list-icon svg{fill:var( --e-global-color-primary );}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );}.elementor-widget-icon-list .elementor-icon-list-text{color:var( --e-global-color-secondary );}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-icon i{color:var( --e-global-color-secondary );transition:color 0.3s;}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-icon svg{fill:var( --e-global-color-secondary );transition:fill 0.3s;}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-item:hover .elementor-icon-list-icon i{color:#E2820A;}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-item:hover .elementor-icon-list-icon svg{fill:#E2820A;}.elementor-356 .elementor-element.elementor-element-a509a6e{--e-icon-list-icon-size:25px;--icon-vertical-offset:0px;}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-item > .elementor-icon-list-text, .elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-item > a{font-family:\"Helvetica\", Sans-serif;font-size:16px;text-transform:capitalize;font-style:oblique;}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-text{color:#FFFFFF;transition:color 0.3s;}@media(max-width:767px){.elementor-356 .elementor-element.elementor-element-24e6347{--align-items:center;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-items:not(.elementor-inline-items) .elementor-icon-list-item:not(:last-child){padding-block-end:calc(1px\/2);}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-items:not(.elementor-inline-items) .elementor-icon-list-item:not(:first-child){margin-block-start:calc(1px\/2);}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-items.elementor-inline-items .elementor-icon-list-item{margin-inline:calc(1px\/2);}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-items.elementor-inline-items{margin-inline:calc(-1px\/2);}.elementor-356 .elementor-element.elementor-element-a509a6e .elementor-icon-list-items.elementor-inline-items .elementor-icon-list-item:after{inset-inline-end:calc(-1px\/2);}.elementor-356 .elementor-element.elementor-element-a509a6e{--e-icon-list-icon-size:25px;--e-icon-list-icon-align:center;--e-icon-list-icon-margin:0 calc(var(--e-icon-list-icon-size, 1em) * 0.125);--icon-vertical-offset:0px;}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"356\" class=\"elementor elementor-356 e-loop-item e-loop-item-5005 post-5005 post type-post status-publish format-standard has-post-thumbnail hentry category-video\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-24e6347 e-flex e-con-boxed e-con e-parent\" data-id=\"24e6347\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72f55e0 elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"72f55e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjYwMiIsInRvZ2dsZSI6ZmFsc2V9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar pedido de informa\u00e7\u00e3o<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65ed0a3 elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"65ed0a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIwMjQiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Whatsapp<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a509a6e elementor-mobile-align-center elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a509a6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook-square\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48A48 48 0 0 0 0 80v352a48 48 0 0 0 48 48h137.25V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.27c-30.81 0-40.42 19.12-40.42 38.73V256h68.78l-11 71.69h-57.78V480H400a48 48 0 0 0 48-48V80a48 48 0 0 0-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-x-twitter-square\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M64 32C28.7 32 0 60.7 0 96V416c0 35.3 28.7 64 64 64H384c35.3 0 64-28.7 64-64V96c0-35.3-28.7-64-64-64H64zm297.1 84L257.3 234.6 379.4 396H283.8L209 298.1 123.3 396H75.8l111-126.9L69.7 116h98l67.7 89.5L313.6 116h47.5zM323.3 367.6L153.4 142.9H125.1L296.9 367.6h26.3z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-pinterest-square\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448 80v352c0 26.5-21.5 48-48 48H154.4c9.8-16.4 22.4-40 27.4-59.3 3-11.5 15.3-58.4 15.3-58.4 8 15.3 31.4 28.2 56.3 28.2 74.1 0 127.4-68.1 127.4-152.7 0-81.1-66.2-141.8-151.4-141.8-106 0-162.2 71.1-162.2 148.6 0 36 19.2 80.8 49.8 95.1 4.7 2.2 7.1 1.2 8.2-3.3.8-3.4 5-20.1 6.8-27.8.6-2.5.3-4.6-1.7-7-10.1-12.3-18.3-34.9-18.3-56 0-54.2 41-106.6 110.9-106.6 60.3 0 102.6 41.1 102.6 99.9 0 66.4-33.5 112.4-77.2 112.4-24.1 0-42.1-19.9-36.4-44.4 6.9-29.2 20.3-60.7 20.3-81.8 0-53-75.5-45.7-75.5 25 0 21.7 7.3 36.5 7.3 36.5-31.4 132.8-36.1 134.5-29.6 192.6l2.2.8H48c-26.5 0-48-21.5-48-48V80c0-26.5 21.5-48 48-48h352c26.5 0 48 21.5 48 48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-tiktok\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448,209.91a210.06,210.06,0,0,1-122.77-39.25V349.38A162.55,162.55,0,1,1,185,188.31V278.2a74.62,74.62,0,1,0,52.23,71.18V0l88,0a121.18,121.18,0,0,0,1.86,22.17h0A122.18,122.18,0,0,0,381,102.39a121.43,121.43,0,0,0,67,20.14Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-446107ac e-flex e-con-boxed e-con e-parent\" data-id=\"446107ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-523e3c81 e-con-full e-flex e-con e-child\" data-id=\"523e3c81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55d2db78 elementor-grid-1 elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"55d2db78\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:&quot;328&quot;,&quot;columns&quot;:1,&quot;columns_tablet&quot;:1,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-328\">.elementor-328 .elementor-element.elementor-element-cb9690f{--display:flex;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-328 .elementor-element.elementor-element-d3e9da7 .elementor-heading-title{font-family:\"Roboto\", Sans-serif;font-size:40px;font-weight:600;color:#FFFFFF;}.elementor-328 .elementor-element.elementor-element-d3e9da7{padding:10px 0px 10px 20px;background-color:#E2820A;}@media(max-width:767px){.elementor-328 .elementor-element.elementor-element-d3e9da7 .elementor-heading-title{font-size:20px;}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"328\" class=\"elementor elementor-328 e-loop-item e-loop-item-5005 post-5005 post type-post status-publish format-standard has-post-thumbnail hentry category-video\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-cb9690f e-flex e-con-boxed e-con e-parent\" data-id=\"cb9690f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3e9da7 elementor-widget elementor-widget-heading\" data-id=\"d3e9da7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CAT\u00c1LOGO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afda38d elementor-widget elementor-widget-html\" data-id=\"afda38d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<style>\r\n.hyc-light-category-nav{\r\n  --hyc-accent:#E28259;\r\n  --hyc-dark:#1f2933;\r\n  --hyc-text:#4b5563;\r\n  --hyc-line:#e7e7e7;\r\n  --hyc-bg:#ffffff;\r\n  max-width:1200px;\r\n  margin:0 auto;\r\n  padding:24px 18px;\r\n  font-family:Roboto, Arial, sans-serif;\r\n}\r\n\r\n.hyc-light-category-grid{\r\n  display:grid;\r\n  grid-template-columns:1fr;\r\n  gap:22px;\r\n}\r\n\r\n.hyc-light-category-card{\r\n  background:var(--hyc-bg);\r\n  border:1px solid var(--hyc-line);\r\n  border-radius:16px;\r\n  padding:24px 26px;\r\n  box-shadow:0 8px 24px rgba(0,0,0,.05);\r\n  transition:transform .25s ease, box-shadow .25s ease, border-color .25s ease;\r\n}\r\n\r\n.hyc-light-category-card:hover{\r\n  transform:translateY(-3px);\r\n  border-color:rgba(226,130,89,.45);\r\n  box-shadow:0 14px 34px rgba(0,0,0,.08);\r\n}\r\n\r\n.hyc-light-category-title{\r\n  margin:0 0 16px;\r\n  padding-bottom:12px;\r\n  font-size:30px;\r\n  line-height:1.25;\r\n  font-weight:600;\r\n  color:var(--hyc-dark);\r\n  border-bottom:2px solid var(--hyc-line);\r\n  position:relative;\r\n}\r\n\r\n.hyc-light-category-title::after{\r\n  content:\"\";\r\n  position:absolute;\r\n  left:0;\r\n  bottom:-2px;\r\n  width:72px;\r\n  height:2px;\r\n  background:var(--hyc-accent);\r\n}\r\n\r\n.hyc-light-category-list{\r\n  list-style:none;\r\n  margin:0;\r\n  padding:0;\r\n}\r\n\r\n.hyc-light-category-list li{\r\n  margin:0;\r\n  border-bottom:1px dotted #d8d8d8;\r\n}\r\n\r\n.hyc-light-category-list li:last-child{\r\n  border-bottom:0;\r\n}\r\n\r\n.hyc-light-category-list a{\r\n  display:flex;\r\n  align-items:center;\r\n  justify-content:space-between;\r\n  gap:14px;\r\n  padding:13px 0;\r\n  font-size:22px;\r\n  line-height:1.35;\r\n  font-weight:500;\r\n  color:var(--hyc-text);\r\n  text-decoration:none;\r\n  transition:color .2s ease, padding-left .2s ease;\r\n}\r\n\r\n.hyc-light-category-list a::after{\r\n  content:\"\u203a\";\r\n  font-size:24px;\r\n  line-height:1;\r\n  color:#b9b9b9;\r\n  transition:color .2s ease, transform .2s ease;\r\n}\r\n\r\n.hyc-light-category-list a:hover{\r\n  color:var(--hyc-accent);\r\n  padding-left:6px;\r\n}\r\n\r\n.hyc-light-category-list a:hover::after{\r\n  color:var(--hyc-accent);\r\n  transform:translateX(4px);\r\n}\r\n\r\n@media (max-width:768px){\r\n  .hyc-light-category-nav{\r\n    max-width:100%;\r\n    padding:18px 14px;\r\n  }\r\n\r\n  .hyc-light-category-grid{\r\n    gap:18px;\r\n  }\r\n\r\n  .hyc-light-category-card{\r\n    padding:18px 18px;\r\n    border-radius:14px;\r\n  }\r\n\r\n  .hyc-light-category-title{\r\n    font-size:20px;\r\n    margin-bottom:10px;\r\n    padding-bottom:10px;\r\n  }\r\n\r\n  .hyc-light-category-list a{\r\n    font-size:16px;\r\n    padding:11px 0;\r\n  }\r\n\r\n  .hyc-light-category-list a::after{\r\n    font-size:20px;\r\n  }\r\n}\r\n<\/style>\r\n\r\n<nav class=\"hyc-light-category-nav\" aria-label=\"Navega\u00e7\u00e3o na categoria Hyclight\">\r\n  <div class=\"hyc-light-category-grid\">\r\n\r\n    <section class=\"hyc-light-category-card\">\r\n      <h2 class=\"hyc-light-category-title\">Produtos<\/h2>\r\n      <ul class=\"hyc-light-category-list\">\r\n        <li><a href=\"https:\/\/hyclight.com\/pt\/categoria\/produtos\/decoracoes-de-natal\/\">Decora\u00e7\u00f5es para o arco de Natal<\/a><\/li>\r\n        <li><a href=\"https:\/\/hyclight.com\/pt\/categoria\/produtos\/luzes-de-natal\/\">Esculturas de luzes de Natal<\/a><\/li>\r\n        <li><a href=\"https:\/\/hyclight.com\/pt\/categoria\/produtos\/ornamentos-de-natal\/\">Ornamentos de Natal<\/a><\/li>\r\n        <li><a href=\"https:\/\/hyclight.com\/pt\/categoria\/produtos\/arvore-de-natal\/\">\u00c1rvores de Natal<\/a><\/li>\r\n        <li><a href=\"https:\/\/hyclight.com\/pt\/categoria\/produtos\/lanternas-de-festa\/\">Lanternas do festival<\/a><\/li>\r\n        <li><a href=\"https:\/\/hyclight.com\/pt\/categoria\/produtos\/poste-de-luz\/\">Luzes com motivos de postes<\/a><\/li>\r\n        <li><a href=\"https:\/\/hyclight.com\/pt\/categoria\/produtos\/luzes-do-ramadao\/\">Luzes do Ramad\u00e3o<\/a><\/li>\r\n      <\/ul>\r\n    <\/section>\r\n\r\n    <section class=\"hyc-light-category-card\">\r\n      <h2 class=\"hyc-light-category-title\">Not\u00edcias<\/h2>\r\n      <ul class=\"hyc-light-category-list\">\r\n        <li><a href=\"https:\/\/hyclight.com\/pt\/categoria\/noticias\/noticias-da-empresa\/\">Not\u00edcias da empresa<\/a><\/li>\r\n        <li><a href=\"https:\/\/hyclight.com\/pt\/categoria\/noticias\/noticias-do-sector\/\">Not\u00edcias do sector<\/a><\/li>\r\n        <li><a href=\"https:\/\/hyclight.com\/pt\/categoria\/noticias\/noticias-sobre-produtos\/\">Not\u00edcias sobre produtos<\/a><\/li>\r\n      <\/ul>\r\n    <\/section>\r\n\r\n  <\/div>\r\n<\/nav>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f2f0737 e-con-full e-flex e-con e-child\" data-id=\"6f2f0737\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d433d4c e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"5d433d4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;start&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"1564687692\" aria-label=\"\u6807\u7b7e\u9875\u7ec4\u4ef6\u64cd\u4f5c\u63d0\u793a\uff1a\u4f7f\u7528 Enter \u6216 Espa\u00e7o \u952e\u6253\u5f00\u9879\u76ee\uff0c\u4f7f\u7528 Escape \u952e\u5173\u95ed\uff0c\u4f7f\u7528\u65b9\u5411\u952e\u8fdb\u884c\u5bfc\u822a\u3002\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-15646876921\" data-tab-title-id=\"e-n-tab-title-15646876921\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-15646876921\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tDescri\u00e7\u00e3o\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-15646876921\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-15646876921\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-53af8960 e-con-full e-flex e-con e-child\" data-id=\"53af8960\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-625fa03a elementor-widget elementor-widget-text-editor\" data-id=\"625fa03a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Luz com motivo de poste 2D de penas azuis para rua exterior, avenida e decora\u00e7\u00e3o festiva<\/strong><\/h2><div class=\"hf-bluepole-wrap\"><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-hero\"><div><p>A nossa luz com motivo de poste 2D Blue Feather foi concebida para projectos de ilumina\u00e7\u00e3o decorativa exterior que necessitam de um estilo visual refinado e de uma forte presen\u00e7a nocturna. Montada em postes de rua e postes de ilumina\u00e7\u00e3o, ajuda a criar uma paisagem urbana mais elegante para estradas urbanas, zonas comerciais, rotas c\u00e9nicas, programas de f\u00e9rias e exposi\u00e7\u00f5es comerciais no exterior.<\/p><p>Com linhas azuis fluidas iluminadas e acentos de estrelas, esta luz com motivo de poste funciona bem tanto para temas festivos como para o embelezamento geral da cidade. A HOYECHI apoia a produ\u00e7\u00e3o direta da f\u00e1brica, o fornecimento por grosso e a personaliza\u00e7\u00e3o de projectos para empreiteiros, munic\u00edpios, distribuidores e compradores de ilumina\u00e7\u00e3o decorativa.<\/p><div class=\"hf-bluepole-keypoints\"><strong>Design azul elegante<\/strong><br \/><strong>Montagem em poste<\/strong><br \/><strong>Fornecimento a granel<\/strong><br \/><strong>Produ\u00e7\u00e3o personalizada<\/strong><\/div><\/div><div><figure id=\"attachment_3285\" aria-describedby=\"caption-attachment-3285\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-3285 size-full\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/STREET-LIGHT-POLE-SHAPE_02.jpg\" alt=\"Inspe\u00e7\u00e3o da qualidade e detalhes do material da luz do motivo do poste de ilumina\u00e7\u00e3o p\u00fablica\" width=\"750\" height=\"1077\" srcset=\"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/STREET-LIGHT-POLE-SHAPE_02.jpg 750w, https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/STREET-LIGHT-POLE-SHAPE_02-209x300.jpg 209w, https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/STREET-LIGHT-POLE-SHAPE_02-713x1024.jpg 713w, https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/STREET-LIGHT-POLE-SHAPE_02-8x12.jpg 8w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-3285\" class=\"wp-caption-text\">Inspe\u00e7\u00e3o de qualidade e materiais selecionados para luzes de motivos de postes de ilumina\u00e7\u00e3o p\u00fablica personalizados.<\/figcaption><\/figure><\/div><\/div><\/section><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-head\"><h2><strong>Porque \u00e9 que as luzes azuis com motivos em postes 2D funcionam bem para projectos decorativos no exterior<\/strong><\/h2><p>Os candeeiros de motivo para postes azuis s\u00e3o uma escolha pr\u00e1tica para ruas e espa\u00e7os p\u00fablicos onde os compradores pretendem um efeito decorativo elegante sem fazer com que o ambiente rodovi\u00e1rio pare\u00e7a demasiado povoado. O seu design repet\u00edvel torna-as ideais para avenidas, alamedas, ruas comerciais, \u00e1reas c\u00e9nicas e grandes programas de ilumina\u00e7\u00e3o exterior que requerem consist\u00eancia e apelo visual.<\/p><\/div><div class=\"hf-bluepole-grid-4\"><div class=\"hf-bluepole-card\"><h3><strong>Identidade de rua elegante<\/strong><\/h3><p>A forma inspirada em penas cria um aspeto mais suave e elegante para postes de ilumina\u00e7\u00e3o e decora\u00e7\u00e3o de vias p\u00fablicas.<\/p><\/div><div class=\"hf-bluepole-card\"><h3><strong>Visibilidade nocturna clara<\/strong><\/h3><p>Os contornos LED e os pormenores das estrelas ajudam o motivo a destacar-se \u00e0 noite em estradas, ruas comerciais e espa\u00e7os para eventos.<\/p><\/div><div class=\"hf-bluepole-card\"><h3><strong>Adequado para repeti\u00e7\u00e3o<\/strong><\/h3><p>Este design \u00e9 eficaz para tra\u00e7ados de ruas longas onde a repeti\u00e7\u00e3o de motivos de postes cria um ritmo decorativo mais forte.<\/p><\/div><div class=\"hf-bluepole-card\"><h3><strong>\u00datil para projectos em massa<\/strong><\/h3><p>\u00c9 um produto pr\u00e1tico para programas de decora\u00e7\u00e3o de exteriores a n\u00edvel grossista, municipal, de empreiteiros e distrital.<\/p><\/div><\/div><\/section><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-strip\"><h2><strong>Fornecimento direto da f\u00e1brica para motivos individuais e programas de decora\u00e7\u00e3o de rua completos<\/strong><\/h2><p>A nossa f\u00e1brica pode suportar n\u00e3o s\u00f3 encomendas de motivos de um s\u00f3 poste, mas tamb\u00e9m planos coordenados de decora\u00e7\u00e3o exterior com arcos a condizer, luzes cruzadas, motivos suspensos e outros produtos de ilumina\u00e7\u00e3o festiva. Isto ajuda os compradores a obterem mais eficientemente, mantendo todo o projeto visualmente consistente.<\/p><\/div><\/section><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-split\"><div class=\"hf-bluepole-scene\"><figure id=\"attachment_3286\" aria-describedby=\"caption-attachment-3286\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-full wp-image-3286\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/STREET-LIGHT-POLE-SHAPE_08.jpg\" alt=\"Inspe\u00e7\u00e3o de qualidade de f\u00e1brica de materiais de ilumina\u00e7\u00e3o de motivos de postes de ilumina\u00e7\u00e3o p\u00fablica\" width=\"750\" height=\"740\" srcset=\"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/STREET-LIGHT-POLE-SHAPE_08.jpg 750w, https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/STREET-LIGHT-POLE-SHAPE_08-300x296.jpg 300w, https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/STREET-LIGHT-POLE-SHAPE_08-12x12.jpg 12w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-3286\" class=\"wp-caption-text\">Materiais selecionados e controlo de qualidade de f\u00e1brica para luzes de motivos para postes de rua exteriores.<\/figcaption><\/figure><\/div><\/div><\/section><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-head\"><h2><strong>Para quem \u00e9 melhor esta luz com motivo de poste azul<\/strong><\/h2><p>Este produto \u00e9 adequado para compradores que necessitam de um item de ilumina\u00e7\u00e3o p\u00fablica decorativa que seja elegante, repet\u00edvel e suficientemente flex\u00edvel para projectos de embelezamento festivo e urbano.<\/p><\/div><div class=\"hf-bluepole-grid-3\"><div class=\"hf-bluepole-card\"><h3><strong>Compradores municipais<\/strong><\/h3><p>Adequado para estradas p\u00fablicas, avenidas, pra\u00e7as, parques e projectos de embelezamento da cidade que necessitem de uma decora\u00e7\u00e3o coordenada do poste.<\/p><\/div><div class=\"hf-bluepole-card\"><h3><strong>Grossistas e distribuidores<\/strong><\/h3><p>Um produto pr\u00e1tico para compras a granel, fornecimento repetido e vendas de ilumina\u00e7\u00e3o exterior espec\u00edficas do mercado.<\/p><\/div><div class=\"hf-bluepole-card\"><h3><strong>Empreiteiros e empresas de projectos<\/strong><\/h3><p>\u00datil para grandes programas de rua, planos de decora\u00e7\u00e3o de bairros, rotas tur\u00edsticas e instala\u00e7\u00f5es de ilumina\u00e7\u00e3o exterior para eventos.<\/p><\/div><\/div><h2>Especifica\u00e7\u00f5es t\u00e9cnicas<\/h2><p>Abaixo est\u00e1 um perfil t\u00e9cnico geral para este candeeiro decorativo com motivo de poste 2D. Os detalhes finais podem ser ajustados de acordo com o layout do projeto, a quantidade e os requisitos de personaliza\u00e7\u00e3o.<\/p><div class=\"hf-bluepole-grid-3\"><div class=\"hf-bluepole-card\"><table class=\"spec-table\"><tbody><tr><td><strong>Nome do produto<\/strong><\/td><td>Pena azul 2D Pole Motif Light<\/td><\/tr><tr><td><strong>Tipo de produto<\/strong><\/td><td>Luz decorativa com motivo para exterior montada em poste<\/td><\/tr><tr><td><strong>Material principal<\/strong><\/td><td>Estrutura met\u00e1lica + sistema de ilumina\u00e7\u00e3o LED<\/td><\/tr><tr><td><strong>Estilo de design<\/strong><\/td><td>Motivo 2D inspirado em penas com acentos de estrelas<\/td><\/tr><tr><td><strong>Cores de ilumina\u00e7\u00e3o<\/strong><\/td><td>Azul, Branco quente, Branco frio, Dourado, Multicolorido ou Personalizado<\/td><\/tr><tr><td><strong>Posi\u00e7\u00e3o de instala\u00e7\u00e3o<\/strong><\/td><td>Postes de rua, postes de ilumina\u00e7\u00e3o, colunas de avenidas, postes decorativos p\u00fablicos<\/td><\/tr><tr><td><strong>Tamanhos dispon\u00edveis<\/strong><\/td><td>Tamanhos personalizados com base nos requisitos do projeto<\/td><\/tr><tr><td><strong>Aplica\u00e7\u00f5es<\/strong><\/td><td>Ruas, avenidas, parques, zonas comerciais, percursos panor\u00e2micos, espa\u00e7os para eventos<\/td><\/tr><tr><td><strong>Tipo de fornecimento<\/strong><\/td><td>Direto da f\u00e1brica \/ Atacado \/ Produ\u00e7\u00e3o personalizada<\/td><\/tr><tr><td><strong>Produtos correspondentes<\/strong><\/td><td>Luzes de cruzamento de ruas, arcos, motivos suspensos, esculturas, conjuntos de expositores festivos<\/td><\/tr><\/tbody><\/table><\/div><\/div><\/section><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-head\"><h2><strong>Especifica\u00e7\u00f5es t\u00e9cnicas<\/strong><\/h2><p>Abaixo est\u00e1 um perfil t\u00e9cnico geral para este candeeiro decorativo com motivo de poste 2D. Os detalhes finais podem ser ajustados de acordo com o layout do projeto, a quantidade e os requisitos de personaliza\u00e7\u00e3o.<\/p><\/div><\/section><\/div><div class=\"hf-bluepole-wrap\"><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-listcols\"><div class=\"hf-bluepole-listbox\"><h3><strong>Op\u00e7\u00f5es de personaliza\u00e7\u00e3o<\/strong><\/h3><ul><li>Podem ser ajustadas linhas em forma de pena, estrelas, curvas abstractas e detalhes decorativos<\/li><li>O azul pode ser combinado com branco, dourado ou outras cores do projeto<\/li><li>Adequado para instala\u00e7\u00f5es espelhadas, unidades repetidas e layouts de rua alternados<\/li><li>Pode ser adaptado a temas festivos, rotas tur\u00edsticas e decora\u00e7\u00e3o de paisagens nocturnas<\/li><li>Apoio \u00e0 produ\u00e7\u00e3o em massa para projectos a n\u00edvel distrital e de longo curso<\/li><\/ul><\/div><div class=\"hf-bluepole-listbox\"><h3><strong>Vantagens da f\u00e1brica<\/strong><\/h3><ul><li>Fabrico direto de produtos de ilumina\u00e7\u00e3o festiva e de exposi\u00e7\u00e3o decorativa exterior<\/li><li>Apoio baseado em desenhos, esbo\u00e7os, fotografias de projectos ou ideias conceptuais<\/li><li>Fornecimento mais eficiente para compradores grossistas e de engenharia<\/li><li>Pode coordenar produtos de ilumina\u00e7\u00e3o exterior relacionados de um \u00fanico fornecedor<\/li><li>Adequado para compras sazonais repetidas e aquisi\u00e7\u00f5es de grandes projectos<\/li><\/ul><\/div><\/div><\/section><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-head\"><h2><strong>\u00c1reas comuns de aplica\u00e7\u00e3o<\/strong><\/h2><p>Este candeeiro com motivo de poste azul \u00e9 adequado tanto para decora\u00e7\u00e3o festiva como para ilumina\u00e7\u00e3o decorativa mais geral da cidade, tornando-o uma escolha flex\u00edvel para uma variedade de ambientes exteriores.<\/p><\/div><div class=\"hf-bluepole-grid-3\"><div class=\"hf-bluepole-card\"><h3><strong>Ruas e avenidas da cidade<\/strong><\/h3><p>Melhora as vias p\u00fablicas, as avenidas centrais e os percursos decorativos da cidade com uma vista nocturna mais elegante.<\/p><\/div><div class=\"hf-bluepole-card\"><h3><strong>Distritos comerciais<\/strong><\/h3><p>Funciona bem em ruas comerciais e zonas pedonais que necessitem de ilumina\u00e7\u00e3o decorativa para promo\u00e7\u00f5es sazonais e ambiente noturno.<\/p><\/div><div class=\"hf-bluepole-card\"><h3><strong>Parques e rotas c\u00e9nicas<\/strong><\/h3><p>Adequado para espa\u00e7os tur\u00edsticos, estradas c\u00e9nicas e \u00e1reas de eventos p\u00fablicos onde a ilumina\u00e7\u00e3o art\u00edstica decorativa ajuda a melhorar a atra\u00e7\u00e3o visual.<\/p><\/div><\/div><\/section><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-head\"><h2><strong>Como apoiamos a sua encomenda<\/strong><\/h2><p>Ajudamos os compradores a passar do conceito \u00e0 produ\u00e7\u00e3o com um processo simples que se adapta tanto a encomendas por grosso como a programas de decora\u00e7\u00e3o de exteriores baseados em projectos.<\/p><\/div><div class=\"hf-bluepole-flow\"><div class=\"hf-bluepole-step\"><h3><strong>Partilhar o seu pedido<\/strong><\/h3><p>Envie-nos o seu mercado-alvo, quantidade, ideia de design, cena de instala\u00e7\u00e3o ou imagem de refer\u00eancia para a luz de motivo de poste azul.<\/p><\/div><div class=\"hf-bluepole-step\"><h3><strong>Confirmar detalhes personalizados<\/strong><\/h3><p>Discutimos as dimens\u00f5es, as cores, a dire\u00e7\u00e3o da disposi\u00e7\u00e3o, o estilo decorativo e os produtos correspondentes relacionados com o seu projeto.<\/p><\/div><div class=\"hf-bluepole-step\"><h3><strong>Organizar a produ\u00e7\u00e3o<\/strong><\/h3><p>Ap\u00f3s a confirma\u00e7\u00e3o, a nossa f\u00e1brica organiza a produ\u00e7\u00e3o e apoia o fornecimento repetido para ruas, bairros e programas de exposi\u00e7\u00e3o exterior.<\/p><\/div><\/div><\/section><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-head\"><h2><strong>Perguntas mais frequentes<\/strong><\/h2><\/div><div class=\"hf-bluepole-faq\"><details><summary>\u00c9 uma f\u00e1brica ou uma empresa comercial?<\/summary><p>Somos um fabricante centrado em produtos de ilumina\u00e7\u00e3o festiva e de exposi\u00e7\u00e3o decorativa, fornecendo fornecimento direto da f\u00e1brica para clientes grossistas e de projeto.<\/p><\/details><details><summary>O design do motivo da vara azul pode ser personalizado?<\/summary><p>Sim. Podemos personalizar o tamanho, a combina\u00e7\u00e3o de cores, os detalhes decorativos e o estilo geral do motivo de acordo com os requisitos do seu projeto.<\/p><\/details><details><summary>Este produto \u00e9 adequado para utiliza\u00e7\u00e3o no exterior?<\/summary><p>Sim. Foi concebido para aplica\u00e7\u00f5es decorativas no exterior, como estradas, postes de ilumina\u00e7\u00e3o, avenidas, zonas comerciais, parques e locais de eventos p\u00fablicos.<\/p><\/details><details><summary>Aceitam quantidades por grosso?<\/summary><p>Sim. Apoiamos a produ\u00e7\u00e3o a granel e por grosso para distribuidores, importadores, empreiteiros, munic\u00edpios e empresas de projectos de ilumina\u00e7\u00e3o decorativa.<\/p><\/details><details><summary>Tamb\u00e9m pode fornecer produtos de decora\u00e7\u00e3o de exterior a condizer?<\/summary><p>Sim. Podemos fornecer produtos relacionados, como arcos, luzes de cruzamento, motivos suspensos e outros artigos de exposi\u00e7\u00e3o festivos ou decorativos.<\/p><\/details><details><summary>Que tipos de projectos utilizam normalmente este produto?<\/summary><p>As utiliza\u00e7\u00f5es t\u00edpicas incluem o embelezamento da cidade, a decora\u00e7\u00e3o de avenidas, exposi\u00e7\u00f5es em ruas comerciais, programas de f\u00e9rias, rotas panor\u00e2micas e projectos de ilumina\u00e7\u00e3o tur\u00edstica.<\/p><\/details><\/div><\/section><section class=\"hf-bluepole-section\"><div class=\"hf-bluepole-cta\"><h2><strong>Precisa de uma nova p\u00e1gina de produto de luz com motivo de polo azul compat\u00edvel com SEO para o seu site independente?<\/strong><\/h2><p>Contacte-nos com o seu design preferido, quantidade e aplica\u00e7\u00e3o do projeto. Podemos fornecer pre\u00e7os diretos de f\u00e1brica, apoio \u00e0 produ\u00e7\u00e3o personalizada e solu\u00e7\u00f5es coordenadas de ilumina\u00e7\u00e3o decorativa exterior para o seu pr\u00f3ximo projeto.<\/p><\/div><\/section><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29510bac e-flex e-con-boxed e-con e-parent\" data-id=\"29510bac\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7649aa51 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"7649aa51\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tPRODUTOS MAIS VENDIDOS\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41cd865d elementor-widget elementor-widget-heading\" data-id=\"41cd865d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produtos quentes sobre a luz com motivo 3D<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b89ff25 elementor-grid-4 elementor-grid-mobile-2 elementor-grid-tablet-2 elementor-widget elementor-widget-loop-grid\" data-id=\"5b89ff25\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:&quot;359&quot;,&quot;columns&quot;:4,&quot;columns_mobile&quot;:2,&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_skin&quot;:&quot;post&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-359\">.elementor-359 .elementor-element.elementor-element-4aa165a{--display:flex;--gap:5px 10px;--row-gap:5px;--column-gap:10px;}.elementor-359 .elementor-element.elementor-element-4aa165a:not(.elementor-motion-effects-element-type-background), .elementor-359 .elementor-element.elementor-element-4aa165a > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-359 .elementor-element.elementor-element-6596033{--display:flex;}.elementor-widget-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );}.elementor-359 .elementor-element.elementor-element-8b43325:hover{--e-transform-scale:1.1;}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-359 .elementor-element.elementor-element-a7a4d50 .elementor-heading-title{font-family:\"Roboto\", Sans-serif;font-size:20px;font-weight:600;color:var( --e-global-color-secondary );}.elementor-359 .elementor-element.elementor-element-a7a4d50 .elementor-heading-title a:hover, .elementor-359 .elementor-element.elementor-element-a7a4d50 .elementor-heading-title a:focus{color:#E28259;}.elementor-359 .elementor-element.elementor-element-a7a4d50 .elementor-heading-title a{transition-duration:0.3s;}.elementor-widget-button .elementor-button{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );background-color:var( --e-global-color-accent );}.elementor-359 .elementor-element.elementor-element-2844a1c .elementor-button{font-family:\"Roboto\", Sans-serif;font-size:20px;font-weight:500;fill:var( --e-global-color-secondary );color:var( --e-global-color-secondary );background-color:#61CE7000;}.elementor-359 .elementor-element.elementor-element-2844a1c .elementor-button:hover, .elementor-359 .elementor-element.elementor-element-2844a1c .elementor-button:focus{color:#E28259;}.elementor-359 .elementor-element.elementor-element-2844a1c .elementor-button:hover svg, .elementor-359 .elementor-element.elementor-element-2844a1c .elementor-button:focus svg{fill:#E28259;}.elementor-359 .elementor-element.elementor-element-2844a1c{margin:0px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;padding:0px 0px 0px 0px;}@media(max-width:767px){.elementor-359 .elementor-element.elementor-element-a7a4d50 .elementor-heading-title{font-size:12px;}.elementor-359 .elementor-element.elementor-element-2844a1c .elementor-button{font-size:12px;}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"359\" class=\"elementor elementor-359 e-loop-item e-loop-item-4241 post-4241 post type-post status-publish format-standard has-post-thumbnail hentry category-christmas-decorations\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-4aa165a e-flex e-con-boxed e-con e-parent\" data-id=\"4aa165a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6596033 e-con-full e-flex e-con e-child\" data-id=\"6596033\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b43325 e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8b43325\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hyclight.com\/pt\/produtos\/decoracoes-de-natal\/luz-de-motivo-de-bola-de-natal-gigante-3d-led-walk-through\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/elementor\/thumbs\/Giant-Christmas-Ornaments-4-rp1py9h7kqg4l2evko40sl6pknu69zpujbh1u4o11c.webp\" title=\"Enfeites de Natal gigantes (4)\" alt=\"Enfeites de Natal gigantes (4)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a4d50 elementor-widget elementor-widget-heading\" data-id=\"a7a4d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hyclight.com\/pt\/produtos\/decoracoes-de-natal\/luz-de-motivo-de-bola-de-natal-gigante-3d-led-walk-through\/\" rel=\"nofollow\">F\u00e1brica de enfeites de Natal gigantes personalizados<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2844a1c elementor-widget elementor-widget-button\" data-id=\"2844a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hyclight.com\/pt\/produtos\/decoracoes-de-natal\/luz-de-motivo-de-bola-de-natal-gigante-3d-led-walk-through\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"359\" class=\"elementor elementor-359 e-loop-item e-loop-item-4213 post-4213 post type-post status-publish format-standard has-post-thumbnail hentry category-christmas-decorations\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-4aa165a e-flex e-con-boxed e-con e-parent\" data-id=\"4aa165a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6596033 e-con-full e-flex e-con e-child\" data-id=\"6596033\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b43325 e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8b43325\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hyclight.com\/pt\/produtos\/decoracoes-de-natal\/luz-de-arco-de-natal-personalizada\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/elementor\/thumbs\/Golden-Arch-Ball-Christmas-Light-Display-2-rozygjdwe5go5ek0lnhuidsmfhvuivjrm14rp1qfr4.webp\" title=\"Exposi\u00e7\u00e3o de luzes de Natal do Golden Arch Ball (2)\" alt=\"Exposi\u00e7\u00e3o de luzes de Natal do Golden Arch Ball (2)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a4d50 elementor-widget elementor-widget-heading\" data-id=\"a7a4d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hyclight.com\/pt\/produtos\/decoracoes-de-natal\/luz-de-arco-de-natal-personalizada\/\" rel=\"nofollow\">Expositor luminoso em arco com bolas decorativas douradas<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2844a1c elementor-widget elementor-widget-button\" data-id=\"2844a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hyclight.com\/pt\/produtos\/decoracoes-de-natal\/luz-de-arco-de-natal-personalizada\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"359\" class=\"elementor elementor-359 e-loop-item e-loop-item-4087 post-4087 post type-post status-publish format-standard has-post-thumbnail hentry category-christmas-tree\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-4aa165a e-flex e-con-boxed e-con e-parent\" data-id=\"4aa165a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6596033 e-con-full e-flex e-con e-child\" data-id=\"6596033\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b43325 e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8b43325\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-de-30-pes\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/elementor\/thumbs\/30ft-christmas-tree-rof3b6lwidvx8nms4dm63oap8na4fa8srr1kfy7y9s.webp\" title=\"\u00c1rvore de Natal de 30 p\u00e9s\" alt=\"\u00c1rvore de Natal de 30 p\u00e9s\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a4d50 elementor-widget elementor-widget-heading\" data-id=\"a7a4d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-de-30-pes\/\" rel=\"nofollow\">\u00c1rvore de Natal de 30 p\u00e9s Decora\u00e7\u00e3o de f\u00e9rias do lobby do hotel e do centro comercial<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2844a1c elementor-widget elementor-widget-button\" data-id=\"2844a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-de-30-pes\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"359\" class=\"elementor elementor-359 e-loop-item e-loop-item-4070 post-4070 post type-post status-publish format-standard has-post-thumbnail hentry category-christmas-tree\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-4aa165a e-flex e-con-boxed e-con e-parent\" data-id=\"4aa165a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6596033 e-con-full e-flex e-con e-child\" data-id=\"6596033\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b43325 e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8b43325\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-gigante-para-exterior-personalizavel-com-leds\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/elementor\/thumbs\/5-rmpml9x7307rxz6sct4sm2jelmyxgbvdhpo7zbsmdc.jpg\" title=\"\u00c1rvore de Natal gigante para exterior\" alt=\"\u00c1rvore de Natal gigante para exterior\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a4d50 elementor-widget elementor-widget-heading\" data-id=\"a7a4d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-gigante-para-exterior-personalizavel-com-leds\/\" rel=\"nofollow\">\u00c1rvore de Natal gigante para exterior, ecr\u00e3 LED personaliz\u00e1vel para f\u00e9rias<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2844a1c elementor-widget elementor-widget-button\" data-id=\"2844a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-gigante-para-exterior-personalizavel-com-leds\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"359\" class=\"elementor elementor-359 e-loop-item e-loop-item-4056 post-4056 post type-post status-publish format-standard has-post-thumbnail hentry category-christmas-tree\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-4aa165a e-flex e-con-boxed e-con e-parent\" data-id=\"4aa165a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6596033 e-con-full e-flex e-con e-child\" data-id=\"6596033\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b43325 e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8b43325\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-para-exterior\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/elementor\/thumbs\/Outdoor-Christmas-Tree-6-rolyjq974i29ir3d6orrcnijytmgt6sl5d1shxajpc.webp\" title=\"\u00c1rvore de Natal para exterior (6)\" alt=\"\u00c1rvore de Natal para exterior (6)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a4d50 elementor-widget elementor-widget-heading\" data-id=\"a7a4d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-para-exterior\/\" rel=\"nofollow\">Luzes de Natal para \u00e1rvores de exterior destinadas a decora\u00e7\u00f5es festivas na cidade<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2844a1c elementor-widget elementor-widget-button\" data-id=\"2844a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-para-exterior\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"359\" class=\"elementor elementor-359 e-loop-item e-loop-item-4047 post-4047 post type-post status-publish format-standard has-post-thumbnail hentry category-christmas-tree\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-4aa165a e-flex e-con-boxed e-con e-parent\" data-id=\"4aa165a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6596033 e-con-full e-flex e-con e-child\" data-id=\"6596033\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b43325 e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8b43325\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-exterior-iluminada-com-decoracao-densa-de-ornamentos\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/elementor\/thumbs\/18-rmm9kx50n0ozub1cer11mdqhziw1cnfz7r9n6n07y8.jpg\" title=\"\u00c1rvore de Natal iluminada para exterior com decora\u00e7\u00e3o densa de ornamentos\" alt=\"\u00c1rvore de Natal iluminada para exterior com bolas de ornamento densas para exibi\u00e7\u00e3o nocturna de f\u00e9rias comerciais\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a4d50 elementor-widget elementor-widget-heading\" data-id=\"a7a4d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-exterior-iluminada-com-decoracao-densa-de-ornamentos\/\" rel=\"nofollow\">\u00c1rvore de Natal iluminada para exterior com decora\u00e7\u00e3o densa de ornamentos<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2844a1c elementor-widget elementor-widget-button\" data-id=\"2844a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-exterior-iluminada-com-decoracao-densa-de-ornamentos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"359\" class=\"elementor elementor-359 e-loop-item e-loop-item-4018 post-4018 post type-post status-publish format-standard has-post-thumbnail hentry category-christmas-tree\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-4aa165a e-flex e-con-boxed e-con e-parent\" data-id=\"4aa165a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6596033 e-con-full e-flex e-con e-child\" data-id=\"6596033\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b43325 e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8b43325\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-gigante-de-interior-com-ornamentos-em-forma-de-estrela\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/elementor\/thumbs\/23-rminijzztmw0zgfm4rtityk88do5k6s247ag91lfls.jpg\" title=\"\u00c1rvore de Natal gigante para interior com decora\u00e7\u00e3o de ornamentos Starburst\" alt=\"\u00c1rvore de Natal gigante de interior com ornamentos em forma de estrela e decora\u00e7\u00e3o com bolas de Natal para exposi\u00e7\u00e3o festiva em centros comerciais\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a4d50 elementor-widget elementor-widget-heading\" data-id=\"a7a4d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-gigante-de-interior-com-ornamentos-em-forma-de-estrela\/\" rel=\"nofollow\">\u00c1rvore de Natal gigante para interior com decora\u00e7\u00e3o de ornamentos Starburst<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2844a1c elementor-widget elementor-widget-button\" data-id=\"2844a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-gigante-de-interior-com-ornamentos-em-forma-de-estrela\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"359\" class=\"elementor elementor-359 e-loop-item e-loop-item-4011 post-4011 post type-post status-publish format-standard has-post-thumbnail hentry category-christmas-tree\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-4aa165a e-flex e-con-boxed e-con e-parent\" data-id=\"4aa165a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6596033 e-con-full e-flex e-con e-child\" data-id=\"6596033\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b43325 e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8b43325\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-exterior-personalizada-para-exposicao-em-lojas-de-luxo\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hyclight.com\/wp-content\/uploads\/elementor\/thumbs\/7-1-rmh1ecwfr2tuxjgt3eq3wx2o35uelmwggsd36vpt8g.jpg\" title=\"\u00c1rvore de Natal exterior personalizada para exposi\u00e7\u00e3o de retalho de luxo\" alt=\"\u00c1rvore de Natal exterior personalizada com ornamentos dourados e brancos para exposi\u00e7\u00e3o de f\u00e9rias em lojas de luxo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a4d50 elementor-widget elementor-widget-heading\" data-id=\"a7a4d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-exterior-personalizada-para-exposicao-em-lojas-de-luxo\/\" rel=\"nofollow\">\u00c1rvore de Natal exterior personalizada para exposi\u00e7\u00e3o de retalho de luxo<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2844a1c elementor-widget elementor-widget-button\" data-id=\"2844a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hyclight.com\/pt\/produtos\/arvore-de-natal\/arvore-de-natal-exterior-personalizada-para-exposicao-em-lojas-de-luxo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Elegante ilumina\u00e7\u00e3o com motivos azuis montada em poste, concebida para estradas festivas, avenidas p\u00fablicas e projectos comerciais de decora\u00e7\u00e3o exterior. A nossa ilumina\u00e7\u00e3o com motivo em poste 2D Blue Feather foi concebida para projectos de ilumina\u00e7\u00e3o decorativa exterior que exigem uma apresenta\u00e7\u00e3o elegante e apelativa na rua. Instalada em postes de ilumina\u00e7\u00e3o e postes de avenidas, acrescenta um efeito visual elegante \u00e0s estradas da cidade, \u00e0s lojas [...]<\/p>","protected":false},"author":3,"featured_media":3275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-3375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pole-light"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.6 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Commercial light pole\u200b - hyclight.com<\/title>\n<meta name=\"description\" content=\"Explore blue 2D pole motif lights for city streets, boulevards, shopping districts, and festive public displays. HOYECHI offers factory-direct outdoor decorative lighting with wholesale supply and custom project support.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commercial light pole\u200b\" \/>\n<meta property=\"og:description\" content=\"Explore blue 2D pole motif lights for city streets, boulevards, shopping districts, and festive public displays. HOYECHI offers factory-direct outdoor decorative lighting with wholesale supply and custom project support.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/\" \/>\n<meta property=\"og:site_name\" content=\"hyclight.com\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-25T07:14:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T06:28:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/14-STREET-LIGHT-POLE-SHAPE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"yangzelin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"yangzelin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/produtos\\\/poste-de-luz\\\/poste-de-iluminacao-comercial\\\/\",\"url\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/produtos\\\/poste-de-luz\\\/poste-de-iluminacao-comercial\\\/\",\"name\":\"Commercial light pole\u200b - hyclight.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/produtos\\\/poste-de-luz\\\/poste-de-iluminacao-comercial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/produtos\\\/poste-de-luz\\\/poste-de-iluminacao-comercial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hyclight.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/14-STREET-LIGHT-POLE-SHAPE.jpg\",\"datePublished\":\"2026-03-25T07:14:27+00:00\",\"dateModified\":\"2026-05-14T06:28:02+00:00\",\"description\":\"Explore blue 2D pole motif lights for city streets, boulevards, shopping districts, and festive public displays. HOYECHI offers factory-direct outdoor decorative lighting with wholesale supply and custom project support.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/produtos\\\/poste-de-luz\\\/poste-de-iluminacao-comercial\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hyclight.com\\\/pt\\\/produtos\\\/poste-de-luz\\\/poste-de-iluminacao-comercial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/produtos\\\/poste-de-luz\\\/poste-de-iluminacao-comercial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hyclight.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/14-STREET-LIGHT-POLE-SHAPE.jpg\",\"contentUrl\":\"https:\\\/\\\/hyclight.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/14-STREET-LIGHT-POLE-SHAPE.jpg\",\"width\":800,\"height\":800,\"caption\":\"Blue feather-style street light pole motif with star details for outdoor festive decoration.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/produtos\\\/poste-de-luz\\\/poste-de-iluminacao-comercial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hyclight.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/hyclight.com\\\/en\\\/category\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pole Motif Lights\",\"item\":\"https:\\\/\\\/hyclight.com\\\/en\\\/category\\\/products\\\/pole-light\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Commercial light pole\u200b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/\",\"name\":\"hyclight.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/#organization\",\"name\":\"hyclight.com\",\"url\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hyclight.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo.webp\",\"contentUrl\":\"https:\\\/\\\/hyclight.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo.webp\",\"width\":168,\"height\":168,\"caption\":\"hyclight.com\"},\"image\":{\"@id\":\"https:\\\/\\\/hyclight.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Poste de ilumina\u00e7\u00e3o comercial - hyclight.com","description":"Explore as luzes azuis com motivo de poste 2D para as ruas da cidade, avenidas, zonas comerciais e exposi\u00e7\u00f5es p\u00fablicas festivas. A HOYECHI oferece ilumina\u00e7\u00e3o decorativa para exterior diretamente da f\u00e1brica com fornecimento por grosso e apoio a projectos personalizados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/","og_locale":"pt_PT","og_type":"article","og_title":"Commercial light pole\u200b","og_description":"Explore blue 2D pole motif lights for city streets, boulevards, shopping districts, and festive public displays. HOYECHI offers factory-direct outdoor decorative lighting with wholesale supply and custom project support.","og_url":"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/","og_site_name":"hyclight.com","article_published_time":"2026-03-25T07:14:27+00:00","article_modified_time":"2026-05-14T06:28:02+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/14-STREET-LIGHT-POLE-SHAPE.jpg","type":"image\/jpeg"}],"author":"yangzelin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"yangzelin","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/","url":"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/","name":"Poste de ilumina\u00e7\u00e3o comercial - hyclight.com","isPartOf":{"@id":"https:\/\/hyclight.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/#primaryimage"},"image":{"@id":"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/#primaryimage"},"thumbnailUrl":"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/14-STREET-LIGHT-POLE-SHAPE.jpg","datePublished":"2026-03-25T07:14:27+00:00","dateModified":"2026-05-14T06:28:02+00:00","description":"Explore as luzes azuis com motivo de poste 2D para as ruas da cidade, avenidas, zonas comerciais e exposi\u00e7\u00f5es p\u00fablicas festivas. A HOYECHI oferece ilumina\u00e7\u00e3o decorativa para exterior diretamente da f\u00e1brica com fornecimento por grosso e apoio a projectos personalizados.","breadcrumb":{"@id":"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/#primaryimage","url":"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/14-STREET-LIGHT-POLE-SHAPE.jpg","contentUrl":"https:\/\/hyclight.com\/wp-content\/uploads\/2026\/03\/14-STREET-LIGHT-POLE-SHAPE.jpg","width":800,"height":800,"caption":"Blue feather-style street light pole motif with star details for outdoor festive decoration."},{"@type":"BreadcrumbList","@id":"https:\/\/hyclight.com\/pt\/produtos\/poste-de-luz\/poste-de-iluminacao-comercial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hyclight.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/hyclight.com\/en\/category\/products\/"},{"@type":"ListItem","position":3,"name":"Pole Motif Lights","item":"https:\/\/hyclight.com\/en\/category\/products\/pole-light\/"},{"@type":"ListItem","position":4,"name":"Commercial light pole\u200b"}]},{"@type":"WebSite","@id":"https:\/\/hyclight.com\/pt\/#website","url":"https:\/\/hyclight.com\/pt\/","name":"hyclight.com","description":"","publisher":{"@id":"https:\/\/hyclight.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hyclight.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hyclight.com\/pt\/#organization","name":"hyclight.com","url":"https:\/\/hyclight.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hyclight.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/hyclight.com\/wp-content\/uploads\/2025\/12\/logo.webp","contentUrl":"https:\/\/hyclight.com\/wp-content\/uploads\/2025\/12\/logo.webp","width":168,"height":168,"caption":"hyclight.com"},"image":{"@id":"https:\/\/hyclight.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/posts\/3375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/comments?post=3375"}],"version-history":[{"count":16,"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/posts\/3375\/revisions"}],"predecessor-version":[{"id":4258,"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/posts\/3375\/revisions\/4258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/media\/3275"}],"wp:attachment":[{"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/media?parent=3375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/categories?post=3375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hyclight.com\/pt\/wp-json\/wp\/v2\/tags?post=3375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}